{"id":12808,"date":"2026-05-01T11:18:27","date_gmt":"2026-05-01T14:18:27","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=12808"},"modified":"2026-05-04T11:21:24","modified_gmt":"2026-05-04T14:21:24","slug":"governo-do-estado-atua-para-combater-fraudes-fiscais-quase-em-tempo-real","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2026\/05\/01\/governo-do-estado-atua-para-combater-fraudes-fiscais-quase-em-tempo-real\/","title":{"rendered":"Governo do Estado atua para combater fraudes fiscais quase em tempo real"},"content":{"rendered":"\n<p><strong><em>Central de Monitoramento de Opera\u00e7\u00f5es da Receita Estadual j\u00e1 realizou 2 mil suspens\u00f5es de inscri\u00e7\u00f5es estaduais irregulares.<\/em><\/strong><\/p>\n\n\n\n<p>O governo do Estado, por meio da Receita Estadual, entrega importantes resultados no enfrentamento \u00e0s fraudes fiscais no Rio Grande do Sul. Desde a cria\u00e7\u00e3o da Central de Monitoramento de Opera\u00e7\u00f5es (CMO), em setembro de 2023, a estrutura alcan\u00e7ou a marca de 2 mil suspens\u00f5es de inscri\u00e7\u00f5es estaduais de empresas irregulares, promovendo o avan\u00e7o do modelo de fiscaliza\u00e7\u00e3o orientado por dados, com foco na antecipa\u00e7\u00e3o de riscos e na interrup\u00e7\u00e3o de irregularidades ainda no in\u00edcio das opera\u00e7\u00f5es.<\/p>\n\n\n\n<p>A atua\u00e7\u00e3o tempestiva tem permitido bloquear opera\u00e7\u00f5es fict\u00edcias e evitar preju\u00edzos relevantes aos cofres p\u00fablicos em ICMS que n\u00e3o seria recolhido, a partir de an\u00e1lises de risco em tempo real e do cruzamento de informa\u00e7\u00f5es sobre contribuintes e suas opera\u00e7\u00f5es. Esse modelo possibilita a identifica\u00e7\u00e3o de desvios de padr\u00e3o e o encaminhamento imediato para triagem e ado\u00e7\u00e3o de medidas, como auditorias, alertas e suspens\u00f5es, entre outros.<\/p>\n\n\n\n<p>Os dados mais recentes mostram essa evolu\u00e7\u00e3o. No primeiro trimestre de 2026, houve um crescimento superior a 70% no n\u00famero de suspens\u00f5es em compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior, refletindo os ganhos operacionais e tecnol\u00f3gicos implementados, como, por exemplo, a qualifica\u00e7\u00e3o da equipe e a inclus\u00e3o de novos ind\u00edcios de fraude. A maior parte das suspens\u00f5es \u00e9 relativa a empresas \u201cnoteiras\u201d, que s\u00e3o constitu\u00eddas de forma fraudulenta e existem apenas no papel para emitir notas fiscais \u201cfrias\u201d sobre opera\u00e7\u00f5es de terceiros.<\/p>\n\n\n\n<p>Outro destaque \u00e9 a atua\u00e7\u00e3o cada vez mais pr\u00f3xima ao fato gerador. Atualmente, cerca de 40% das suspens\u00f5es ocorrem em at\u00e9 90 dias ap\u00f3s a abertura da empresa, indicando maior efetividade na preven\u00e7\u00e3o de fraudes antes que gerem preju\u00edzos. Ao mesmo tempo, a CMO mant\u00e9m monitoramento cont\u00ednuo sobre a base de contribuintes, alcan\u00e7ando tamb\u00e9m empresas com mais tempo de inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>Integra\u00e7\u00e3o \u00e9 o caminho &#8211;<\/em><\/strong> Al\u00e9m disso, a Central vem ampliando a coopera\u00e7\u00e3o com outros fiscos estaduais, com o interc\u00e2mbio de informa\u00e7\u00f5es sobre empresas suspeitas e o enfrentamento a esquemas interestaduais. A atua\u00e7\u00e3o da \u00e1rea alcan\u00e7a todo o territ\u00f3rio ga\u00facho, inclusive regi\u00f5es de dif\u00edcil acesso, por meio do uso de intima\u00e7\u00f5es eletr\u00f4nicas e procedimentos remotos, para buscar mais agilidade e efetividade.<\/p>\n\n\n\n<p>A integra\u00e7\u00e3o \u00e9 um dos pilares da atua\u00e7\u00e3o da Central. As suspens\u00f5es realizadas geram subs\u00eddios qualificados para as demais \u00e1reas especializadas da Receita Estadual. Isso contribui para a identifica\u00e7\u00e3o de estruturas fraudulentas mais complexas e para o desencadeamento de opera\u00e7\u00f5es fiscais e investiga\u00e7\u00f5es. A participa\u00e7\u00e3o em a\u00e7\u00f5es como a Opera\u00e7\u00e3o Ozark e iniciativas no setor de bebidas mostram a import\u00e2ncia dessa articula\u00e7\u00e3o no combate \u00e0 sonega\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>CMO e Receita 2030+<\/em><\/strong> &#8211; Criada no \u00e2mbito do Receita 2030+, programa do governo do Estado de moderniza\u00e7\u00e3o da administra\u00e7\u00e3o tribut\u00e1ria ga\u00facha, a CMO \u00e9 uma estrutura operacional de fiscaliza\u00e7\u00e3o da Receita Estadual que, a partir de uma base de dados, faz cruzamento de informa\u00e7\u00f5es sobre empresas e seus s\u00f3cios e emite alertas quando h\u00e1 ind\u00edcios de irregularidades nas empresas e nas opera\u00e7\u00f5es. O objetivo central \u00e9 promover a conformidade tribut\u00e1ria e combater a sonega\u00e7\u00e3o e a concorr\u00eancia desleal entre empresas, tornando o ambiente de neg\u00f3cios mais justo e saud\u00e1vel.<\/p>\n\n\n\n<p>Desde sua cria\u00e7\u00e3o, a \u00e1rea vem ampliando a capacidade de detec\u00e7\u00e3o com o aprimoramento cont\u00ednuo de ind\u00edcios de fraude, incluindo a r\u00e1pida identifica\u00e7\u00e3o de movimenta\u00e7\u00f5es at\u00edpicas de notas fiscais, transa\u00e7\u00f5es com clientes e fornecedores suspeitos e inconsist\u00eancias cadastrais. Os resultados recentes tamb\u00e9m s\u00e3o resultado da cont\u00ednua qualifica\u00e7\u00e3o da equipe, com aloca\u00e7\u00e3o de novos colegas e intensifica\u00e7\u00e3o da integra\u00e7\u00e3o com \u00e1reas internas e outras unidades da federa\u00e7\u00e3o. <em>(fonte: Receita Estadual).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Central de Monitoramento de Opera\u00e7\u00f5es da Receita Estadual j\u00e1 realizou 2 mil suspens\u00f5es de inscri\u00e7\u00f5es estaduais irregulares. O governo do Estado, por meio da Receita Estadual, entrega importantes resultados no enfrentamento \u00e0s fraudes fiscais no Rio Grande do Sul. Desde a cria\u00e7\u00e3o da Central de Monitoramento de Opera\u00e7\u00f5es (CMO), em setembro de 2023, a estrutura [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-12808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-grande-do-sul"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12808"}],"version-history":[{"count":1,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12808\/revisions"}],"predecessor-version":[{"id":12810,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12808\/revisions\/12810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media\/12809"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}