{"id":11871,"date":"2026-02-02T16:11:22","date_gmt":"2026-02-02T19:11:22","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=11871"},"modified":"2026-02-05T16:22:10","modified_gmt":"2026-02-05T19:22:10","slug":"santa-rosa-policia-civil-investiga-ataque-a-tiros-que-resultou-na-morte-de-mulher-e-em-ferimentos-graves-em-crianca","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2026\/02\/02\/santa-rosa-policia-civil-investiga-ataque-a-tiros-que-resultou-na-morte-de-mulher-e-em-ferimentos-graves-em-crianca\/","title":{"rendered":"SANTA ROSA: Pol\u00edcia Civil investiga ataque a tiros que resultou na morte de mulher e em ferimentos graves em crian\u00e7a"},"content":{"rendered":"\n<p>Uma mulher de 33 anos morreu e uma crian\u00e7a de quatro anos ficou ferida em um ataque a tiros ocorrido na noite de domingo (<em>1\u00b0<\/em>) em Santa Rosa. Ela foi identificada como Marta Beatriz Buzzin. Segundo a Brigada Militar, a corpora\u00e7\u00e3o foi acionada por volta das 20h20min e ao chegar no local, as duas v\u00edtimas estavam sendo socorridas pelo Corpo de Bombeiros com ferimentos de arma de fogo. Conforme relato de testemunhas \u00e0 pol\u00edcia, os autores dos disparos seriam indiv\u00edduos encapuzados que fugiram em um ve\u00edculo preto ap\u00f3s o crime. A mulher foi socorrida, mas morreu no hospital. A crian\u00e7a passou por cirurgia e permanece internada em estado grave na UTI pedi\u00e1trica do Hospital Vida e Sa\u00fade. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, a motiva\u00e7\u00e3o do crime seria o envolvimento da mulher com uma fac\u00e7\u00e3o criminosa que atua na regi\u00e3o. A investiga\u00e7\u00e3o trabalha para identificar e localizar os autores do ataque. <em>(Portal Plural\/ GZH)<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher de 33 anos morreu e uma crian\u00e7a de quatro anos ficou ferida em um ataque a tiros ocorrido na noite de domingo (1\u00b0) em Santa Rosa. Ela foi identificada como Marta Beatriz Buzzin. Segundo a Brigada Militar, a corpora\u00e7\u00e3o foi acionada por volta das 20h20min e ao chegar no local, as duas v\u00edtimas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-11871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11871"}],"version-history":[{"count":1,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11871\/revisions"}],"predecessor-version":[{"id":11873,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11871\/revisions\/11873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media\/11872"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}