{"id":11817,"date":"2026-02-02T15:48:43","date_gmt":"2026-02-02T18:48:43","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=11817"},"modified":"2026-02-05T15:51:19","modified_gmt":"2026-02-05T18:51:19","slug":"transito-fiscalizacao-e-abordagens-policiais-marcam-o-final-de-semana-panambiense","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2026\/02\/02\/transito-fiscalizacao-e-abordagens-policiais-marcam-o-final-de-semana-panambiense\/","title":{"rendered":"TR\u00c2NSITO: Fiscaliza\u00e7\u00e3o e abordagens policiais marcam o final de semana panambiense"},"content":{"rendered":"\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Uma s\u00e9rie de a\u00e7\u00f5es ostensivas desencadeadas pela Brigada Militar de Panambi no \u00faltimo final de semana, teve por objetivo coibir excessos e abusos na condu\u00e7\u00e3o de ve\u00edculos automotores em \u00e1reas consideradas de vulnerabilidade e frequentei a ocorr\u00eancia de turba\u00e7\u00f5es de tr\u00e2nsito em nosso munic\u00edpio. Os atos fiscalizat\u00f3rios fazem parte de um plano integrado da pol\u00edcia militar estadual, buscando a efetividade, a pacifica\u00e7\u00e3o, e a diminui\u00e7\u00e3o consider\u00e1vel do n\u00famero de acidentes em vias p\u00fablicas dos munic\u00edpios fiscalizados. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Em pelo menos duas a\u00e7\u00f5es desencadeadas em nosso munic\u00edpio, ve\u00edculos foram abordados, fiscalizados e autuados frente a poss\u00edveis irregularidades constatadas. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Caso id\u00eantico ao descrito ocorreu na madrugada de domingo (<em>01<\/em>), onde uma patrulha que se deslocava pelo bairro Arco-\u00cdris, visualizou duas motocicletas circulando com as luzes baixas apagadas e escapamentos esportivos extremamente barulhentos, cujo som podia ser ouvido h\u00e1 v\u00e1rias quadras de dist\u00e2ncia. Os policiais tentaram realizar a abordagem, que n\u00e3o foi obedecida pelos condutores, que se evadiram em fuga pela via p\u00fablica. Abordados no bairro Esperan\u00e7a, foi constatado que um dos condutores n\u00e3o possu\u00eda Carteira Nacional de Habilita\u00e7\u00e3o. Tamb\u00e9m foi verificado que as motocicletas estavam equipadas com escapamentos esportivos n\u00e3o originais, de alto ru\u00eddo, al\u00e9m de espelhos retrovisores abaixados, o que os tornava ineficientes e inoperantes. As motos foram recolhidas ao dep\u00f3sito do guincho e 06 autos de infra\u00e7\u00e3o foram registrados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Uma s\u00e9rie de a\u00e7\u00f5es ostensivas desencadeadas pela Brigada Militar de Panambi no \u00faltimo final de semana, teve por objetivo coibir excessos e abusos na condu\u00e7\u00e3o de ve\u00edculos automotores em \u00e1reas consideradas de vulnerabilidade e frequentei a ocorr\u00eancia de turba\u00e7\u00f5es de tr\u00e2nsito em nosso munic\u00edpio. Os atos fiscalizat\u00f3rios fazem parte de um plano integrado da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-11817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11817"}],"version-history":[{"count":1,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11817\/revisions"}],"predecessor-version":[{"id":11819,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11817\/revisions\/11819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media\/11818"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}