{"id":10678,"date":"2025-10-10T13:40:17","date_gmt":"2025-10-10T16:40:17","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=10678"},"modified":"2025-10-10T13:40:17","modified_gmt":"2025-10-10T16:40:17","slug":"estado-reduz-em-39-o-tempo-medio-de-espera-por-consulta-em-reumatologia-no-rio-grande-do-sul","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2025\/10\/10\/estado-reduz-em-39-o-tempo-medio-de-espera-por-consulta-em-reumatologia-no-rio-grande-do-sul\/","title":{"rendered":"Estado reduz em 39% o tempo m\u00e9dio de espera por consulta em reumatologia no Rio Grande do Sul"},"content":{"rendered":"\n<p><strong><em>A\u00e7\u00e3o da Secretaria da Sa\u00fade, com o apoio do Telessa\u00fadeRS, diminui filas e qualifica o atendimento aos pacientes.<\/em><\/strong><\/p>\n\n\n\n<p>O governo do Estado, por meio da Secretaria da Sa\u00fade (SES), vem fortalecendo o acesso a consultas e procedimentos especializados em diversas \u00e1reas pelo Sistema \u00danico de Sa\u00fade (SUS), como \u00e9 o caso da reumatologia. Entre dezembro de 2024 e agosto de 2025, a m\u00e9dia do tempo de espera para consulta diminuiu de 56 dias para 34 dias, uma redu\u00e7\u00e3o de 39%.<\/p>\n\n\n\n<p>A redu\u00e7\u00e3o \u00e9 fruto da amplia\u00e7\u00e3o do trabalho de regula\u00e7\u00e3o ambulatorial realizado pela SES em parceria com o Telessa\u00fadeRS, com impactos positivos em diversas especialidades. A a\u00e7\u00e3o integra o projeto RegulaSUS, ferramenta fundamental para otimizar fluxos assistenciais, garantir acesso oportuno e promover um SUS mais eficiente e resolutivo em todo o Estado.<\/p>\n\n\n\n<p>Historicamente, o tempo na fila para consultas em reumatologia \u00e9 relativamente longo. Por outro lado, boa parte dos problemas apresentados pelos pacientes podem ser resolvidos diretamente na aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS). Por ser uma especialidade essencialmente cl\u00ednica \u2013 que n\u00e3o depende de alta tecnologia para a maioria dos diagn\u00f3sticos e dos tratamentos \u2013, o acesso a um m\u00e9dico qualificado pode evitar agravamentos da doen\u00e7a e melhorar significativamente a qualidade de vida dos pacientes.<\/p>\n\n\n\n<p>A atua\u00e7\u00e3o da SES, em parceria com o Telessa\u00fadeRS, est\u00e1 garantindo cuidados precoces adequados aos pacientes. A estrat\u00e9gia combina an\u00e1lise de todos os casos encaminhados para a especialidade, prioriza\u00e7\u00e3o de consultas para aqueles considerados mais graves e teleconsultorias de apoio para os profissionais da APS. Com isso, muitos pacientes s\u00e3o acompanhados nos munic\u00edpios onde moram, sem necessidade de deslocamento para centros de refer\u00eancia. <em>(fonte: Ascom SES).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o da Secretaria da Sa\u00fade, com o apoio do Telessa\u00fadeRS, diminui filas e qualifica o atendimento aos pacientes. O governo do Estado, por meio da Secretaria da Sa\u00fade (SES), vem fortalecendo o acesso a consultas e procedimentos especializados em diversas \u00e1reas pelo Sistema \u00danico de Sa\u00fade (SUS), como \u00e9 o caso da reumatologia. Entre dezembro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-10678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10678"}],"version-history":[{"count":0,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}