{"id":10354,"date":"2025-09-09T14:58:20","date_gmt":"2025-09-09T17:58:20","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=10354"},"modified":"2025-09-09T14:58:20","modified_gmt":"2025-09-09T17:58:20","slug":"panambi-onda-de-estelionatos-e-investigado-pela-policia-civil","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2025\/09\/09\/panambi-onda-de-estelionatos-e-investigado-pela-policia-civil\/","title":{"rendered":"PANAMBI: Onda de estelionatos \u00e9 investigado pela Pol\u00edcia Civil"},"content":{"rendered":"\n<p>V\u00e1rios registros de estelionato e tentativa de estelionato foram feitos na Delegacia de Pol\u00edcia de Panambi na semana passada. Uma modalidade de golpe registrado na Cidade das M\u00e1quinas, a v\u00edtima recebeu mensagens de um n\u00famero desconhecido, alegando que o seu celular est\u00e1 estragado, mas que utiliza a foto de perfil do familiar. O suposto parente solicita ajuda para o pagamento de boletos e transfer\u00eancias via Pix, alegando que o limite banc\u00e1rio estaria excedido e que devolveria os valores no dia seguinte. Em alguns casos, segundo as informa\u00e7\u00f5es, as v\u00edtimas chegaram a encaminhar os valores solicitados. Somente mais tarde ao entrarem em contato com o familiar que supostamente havia solicitado o envio do PIX, e diante da negativa, as v\u00edtimas constatou tratar-se de estelionato.<\/p>\n\n\n\n<p>Outros registros feitos na Delegacia de Pol\u00edcia de Panambi d\u00e3o conta de que os estelionat\u00e1rios se passam pela pr\u00f3pria v\u00edtima. Esta modalidade se relaciona \u00e0 clonagem do WhatsApp. Depois de sequestrar a conta da v\u00edtima, o golpista passa a usar fotos suas, obtidas em redes sociais. Em seguida, ele passa a procurar os contatos da v\u00edtima. Como o n\u00famero de celular \u00e9 desconhecido, ele alega que teve de troc\u00e1-lo, dizendo estar em uma emerg\u00eancia, e pede uma transfer\u00eancia via Pix. A Pol\u00edcia Civil alerta para o cuidado com a exposi\u00e7\u00e3o de dados em redes sociais.&nbsp; \u00c9 preciso ficar atento quando receber mensagens de contatos com n\u00fameros novos, especialmente se eles pedirem dinheiro com urg\u00eancia. Antes de fazer um Pix, o recomend\u00e1vel \u00e9 entrar em contato com a pessoa por chamada telef\u00f4nica ou pessoalmente. <em>(Adapta\u00e7\u00e3o NV\/ R\u00e1dio Sulbrasileira)<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e1rios registros de estelionato e tentativa de estelionato foram feitos na Delegacia de Pol\u00edcia de Panambi na semana passada. Uma modalidade de golpe registrado na Cidade das M\u00e1quinas, a v\u00edtima recebeu mensagens de um n\u00famero desconhecido, alegando que o seu celular est\u00e1 estragado, mas que utiliza a foto de perfil do familiar. O suposto parente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-10354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10354"}],"version-history":[{"count":0,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}