{"id":10349,"date":"2025-09-09T14:55:27","date_gmt":"2025-09-09T17:55:27","guid":{"rendered":"https:\/\/anoticiadovale.com.br\/?p=10349"},"modified":"2025-09-09T14:55:27","modified_gmt":"2025-09-09T17:55:27","slug":"crime-organizado-acao-da-brigada-militar-no-bairro-sao-jorge-detem-usuarios-e-apreende-drogas-municoes-e-submetralhadora-de-uso-restrito","status":"publish","type":"post","link":"https:\/\/anoticiadovale.com.br\/index.php\/2025\/09\/09\/crime-organizado-acao-da-brigada-militar-no-bairro-sao-jorge-detem-usuarios-e-apreende-drogas-municoes-e-submetralhadora-de-uso-restrito\/","title":{"rendered":"CRIME ORGANIZADO: A\u00e7\u00e3o da Brigada Militar no bairro S\u00e3o Jorge, det\u00e9m usu\u00e1rios e apreende drogas, muni\u00e7\u00f5es e submetralhadora de uso restrito"},"content":{"rendered":"\n<p>Na noite do s\u00e1bado (<em>06<\/em>), a Brigada Militar, por meio da For\u00e7a T\u00e1tica do 39\u00ba BPM, realizou uma apreens\u00e3o de drogas, armas e diversos objetos em uma resid\u00eancia localizada na Rua Olaria, bairro S\u00e3o Jorge, em Panambi. Durante patrulhamento, os policiais visualizaram dois indiv\u00edduos em frente a um im\u00f3vel. Ao perceberem a presen\u00e7a da viatura, os homens entraram rapidamente na casa e sa\u00edram logo em seguida em um ve\u00edculo. O carro foi abordado e, em seu interior, encontrada uma por\u00e7\u00e3o de maconha.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Simultaneamente, outro indiv\u00edduo que estava em frente ao im\u00f3vel correu para os fundos da resid\u00eancia. Os policiais ent\u00e3o visualizaram papelotes de coca\u00edna. Na a\u00e7\u00e3o, foram apreendidos 01 submetralhadora de uso militar restrito sem numera\u00e7\u00e3o; 01 carregador; 43 muni\u00e7\u00f5es&nbsp; calibre 9mm; 02 muni\u00e7\u00f5es calibre 38mm; 02 c\u00e1psulas calibre 32mm; 104 papelotes de coca\u00edna, totalizando 80 gramas; 02 por\u00e7\u00f5es de maconha, totalizando 15 gramas; 01 faca com bainha; 08 celulares; 01 cooler; 18 cigarros eletr\u00f4nicos; 01 balan\u00e7a de precis\u00e3o; 02 cart\u00f5es de cr\u00e9dito; 01 c\u00e2mera de seguran\u00e7a; materiais para emalar drogas, denotando a franca comercializa\u00e7\u00e3o; e R$ 192,00 em esp\u00e9cie. O caso foi registrado na Delegacia de Pol\u00edcia, onde os objetos e entorpecentes foram apresentados para os devidos procedimentos legais.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A investiga\u00e7\u00e3o policial, de posse de anota\u00e7\u00f5es, documentos de identidade e cr\u00e9dito localizados no momento da apreens\u00e3o, investiga a posse, propriedade e responsabilidade sobre os il\u00edcitos e o armamento b\u00e9lico localizado no im\u00f3vel. Al\u00e9m do propriet\u00e1rio, que fora acionado para prestar esclarecimentos, outras duas pessoas ser\u00e3o chamadas para que prestem depoimento formal. A Pol\u00edcia Civil n\u00e3o descarta a possibilidade de que o local fosse um centro de distribui\u00e7\u00e3o de entorpecentes de um grupo criminoso organizado, com bra\u00e7os estabelecidos no munic\u00edpio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite do s\u00e1bado (06), a Brigada Militar, por meio da For\u00e7a T\u00e1tica do 39\u00ba BPM, realizou uma apreens\u00e3o de drogas, armas e diversos objetos em uma resid\u00eancia localizada na Rua Olaria, bairro S\u00e3o Jorge, em Panambi. Durante patrulhamento, os policiais visualizaram dois indiv\u00edduos em frente a um im\u00f3vel. Ao perceberem a presen\u00e7a da viatura, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-10349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete"],"_links":{"self":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10349"}],"version-history":[{"count":0,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiadovale.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}